{"id":2811,"date":"2023-03-14T18:52:27","date_gmt":"2023-03-14T17:52:27","guid":{"rendered":"https:\/\/highupme.com\/?p=2811"},"modified":"2025-02-09T13:02:25","modified_gmt":"2025-02-09T12:02:25","slug":"arbre-de-vie","status":"publish","type":"post","link":"https:\/\/highupme.com\/en\/arbre-de-vie\/","title":{"rendered":"L&rsquo;arbre de vie"},"content":{"rendered":"[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbsection\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row admin_label=\u00a0\u00bbrow\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbText\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<p><\/p>\n<p><strong>L\u2019arbre de vie<\/strong>\u00a0est un outil que nous utilisons souvent avec nos clients. C\u2019est avant tout un excellent outil de partage bas\u00e9 sur les pratiques narratives et de soutien. Voyez les diff\u00e9rentes parties qui composent l\u2019arbre comme une m\u00e9taphore pour repr\u00e9senter les diff\u00e9rentes parties de votre vie.<\/p>\n<p><\/p>\n<p><\/p>\n<h3 class=\"wp-block-heading\"><strong>Explication<\/strong><\/h3>\n<p><\/p>\n<p><\/p>\n<p>Imaginez un arbre avec tout ce qui le compose et vous obtenez ceci:<\/p>\n<ul>\n<li><strong>Les racines<\/strong> repr\u00e9sentent vos\u00a0origines, vos particularit\u00e9s, vos valeurs, vos passions et ce qui vous a fait grandir<\/li>\n<li><strong>Le tronc<\/strong> repr\u00e9sente vos\u00a0ressources, vos comp\u00e9tences, vos qualit\u00e9s, vos forces et ce que vous avez acquis<\/li>\n<li><strong>Les grosses<\/strong>\u00a0<strong>branches<\/strong> repr\u00e9sentent vos\u00a0objectifs, vos projets \u00e0 long terme, vos espoirs et aspirations<\/li>\n<li><strong>Les petites branches<\/strong> repr\u00e9sentent vos\u00a0petits objectifs et d\u00e9fis du quotidien<\/li>\n<li><strong>Les feuilles repr\u00e9sentent<\/strong> le personnes importantes de votre vie et les ressources autour de vous<\/li>\n<li><strong>Les fruits et les fleurs<\/strong>\u00a0repr\u00e9sentent vos r\u00e9sultats et les rencontres qui ont influenc\u00e9 votre vie de mani\u00e8re positive<\/li>\n<\/ul>\n<p><\/p>\n<p><!-- \/wp:post-content --><\/p>\n<p><!-- wp:heading {\"level\":3} --><\/p>\n<h3 class=\"wp-block-heading\"><strong>For whom and why?<\/strong><\/h3>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Cet outil peut \u00eatre utilis\u00e9 \u00e0 tous les niveaux, qu\u2019ils soient d\u2019ordres personnels ou professionnels, en groupe ou en famille. Lors de notre s\u00e9ance de coaching\u00a0<strong>Coaching<\/strong>\u00a0nous appliquons l\u2019art du questionnement justement et soigneusement formul\u00e9. De cette mani\u00e8re nous vous invitons \u00e0 faire un \u00e9tat des lieux de votre parcours avec un regard nouveau.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:image {\"id\":1488,\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} --><\/p>\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/i0.wp.com\/highupme.com\/wp-content\/uploads\/2022\/11\/questioning.png?resize=800%2C534&#038;ssl=1\" alt=\"\" class=\"wp-image-1488\" srcset=\"https:\/\/highupme.com\/wp-content\/uploads\/2022\/11\/questioning.png 800w, https:\/\/highupme.com\/wp-content\/uploads\/2022\/11\/questioning-480x320.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><\/figure>\n<p><!-- \/wp:image --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Vous pouvez utiliser de plusieurs fa\u00e7ons votre arbre de vie. Le domaines les plus courants sont:<\/p>\n<ul>\n<li>Booster et restaurer l\u2019estime de soi (<em>exemple mis en avant aujourd\u2019hui<\/em>).<\/li>\n<li>Se projeter dans l\u2019avenir.<\/li>\n<li>Mieux se conna\u00eetre.<\/li>\n<li>Mettre en place un projet.<\/li>\n<li>Identifier les turbulences dans votre vie.<\/li>\n<li>Op\u00e9rer une r\u00e9orientation professionnelle.<\/li>\n<li>Changer de strat\u00e9gie.<\/li>\n<li>Pr\u00e9venir, identifier et d\u00e9nouer des conflits.<\/li>\n<li>D\u00e9velopper la coh\u00e9sion d\u2019\u00e9quipes.<\/li>\n<li>Construire ensemble une nouvelle fa\u00e7on de travailler.<\/li>\n<li>Donner des feedbacks positifs et SMART.<\/li>\n<li>etc \u2026<\/li>\n<\/ul>\n<p>Comme vous l\u2019aurez tr\u00e8s certainement compris, l\u2019arbre de vie est un outil qui s\u2019adapte en fonction de votre demande et de vos attentes. En outre, vous n\u2019aurez pas besoin d\u2019une multitude de s\u00e9ances pour redonner du sens \u00e0 vos exp\u00e9riences pass\u00e9es de fa\u00e7on cr\u00e9ative et ludique, une seule suffira!<\/p>\n<p>Cet exercice est un excellent moyen de d\u00e9finir votre objectif global et ainsi de poser la trame de votre accompagnement avec nous pour vos futures s\u00e9ances\u00a0<strong>high up me.<\/strong><\/p>\n<p><strong><\/strong><\/p>\n<p><strong>Quels sont vos b\u00e9n\u00e9fices ?<\/strong><\/p>\n<ul>\n<li>Augmenter votre estime de soi.<\/li>\n<li>Mettre en avant vos valeurs.<\/li>\n<li>Faire \u00e9merger vos ressources.<\/li>\n<li>Avoir une vision plus claire, positive et plus objective de votre avenir.<\/li>\n<li>Retrouvez l\u2019envie et le plaisir d\u2019agir et d\u2019avancer.<\/li>\n<li>Transformer une exp\u00e9rience n\u00e9gative en un projet positif.<\/li>\n<li>Booster votre confiance en vous.<\/li>\n<li>Retrouver du sens.<\/li>\n<li>Prendre conscience de vos comp\u00e9tences, vos talents et vos forces.<\/li>\n<li>Trouver des pistes de r\u00e9orientation de mani\u00e8re plus cr\u00e9ative que le bilan de comp\u00e9tences habituel.<\/li>\n<li>Rendre accessible vos projets et vos r\u00eaves.<\/li>\n<li>Passer \u00e0 l\u2019action et devenir l\u2019acteur de votre vie.<\/li>\n<li>Devenir la meilleure version de vous-m\u00eame.<\/li>\n<li>Fixer vos limites.<\/li>\n<li>Vous remettre en question.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>L\u2019arbre de vie est un super activateur d\u2019estime de soi et de confiance en soi ! C\u2019est un bon coup de Boost dans la r\u00e9alisation de vos objectifs !<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:heading {\"level\":3} --><\/p>\n<h3 class=\"wp-block-heading\"><strong>Exercice \u00ab\u00a0L\u2019arbre de l\u2019estime de soi\u00a0\u00bb<\/strong><\/h3>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Je vous explique ci-dessous comment utiliser l\u2019arbre de vie afin de booster votre facteur estime de soi.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><strong>Ce mode d\u2019emploi est une des fa\u00e7ons d\u2019utiliser l\u2019arbre de vie. Il peut \u00eatre adapt\u00e9 et modifi\u00e9 en fonction de vos besoins. N\u2019h\u00e9sitez pas \u00e0 faire appel \u00e0 nous pour vos demandes de coaching et ensemble nous verrons ce qui vous convient le mieux en fonction de votre demande.<\/strong><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Pour bien r\u00e9aliser votre arbre de l\u2019estime de soi vous aurez besoin de quelques outils essentiels.<\/p>\n<ul>\n<li>3 feuilles de papier.<\/li>\n<li>1 crayon gris et une gomme.<\/li>\n<li>Des feutres ou des crayons de couleur.<\/li>\n<li>Sur la premi\u00e8re feuille dressez une liste de vos qualit\u00e9s.<\/li>\n<li>Sur la deuxi\u00e8me, faites une liste de vos r\u00e9ussites.<\/li>\n<li>Sur la troisi\u00e8me, dessinez votre arbre.<\/li>\n<li>Tout d\u2019abord, dessinez le sol qui servira comme tout le monde le sait \u00e0 nourrir les racines de votre arbre et cr\u00e9er la s\u00e8ve.<\/li>\n<li>Dessinez les racines de l\u2019arbre, bien \u00e9videment en dessous du sol nous sommes bien d\u2019accord. Elles lui permettront d\u2019assimiler les nutriments.<\/li>\n<li>Ensuite vient le tronc. Il s\u2019\u00e9l\u00e8ve vers le ciel en devenant de plus en plus fort, ancr\u00e9 et plein de vie.<\/li>\n<li>Maintenant viennent les branches qui s\u2019\u00e9tirent dans toutes les directions.<\/li>\n<li>Les feuilles quant \u00e0 elles, sont l\u2019habit qui tient bon chaud si on part du principe que nous ne sommes ni en automne ni en hiver.<\/li>\n<li>Et pour fini, cerise sur le Sundae, vous ajouterez les fleurs qui embelliront votre arbre et lui donneront les couleurs qui feront toute sa grandeur.<\/li>\n<li>A c\u00f4t\u00e9 de chaque fleur, inscrivez une r\u00e9ussite.<\/li>\n<li>A c\u00f4t\u00e9 de chaque racine, inscrivez une qualit\u00e9.<\/li>\n<\/ul>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:list {\"ordered\":true} --><\/p>\n<ol>\n<ol><!-- wp:list-item --><\/ol>\n<\/ol>\n<ul><\/ul>\n<p><!-- \/wp:list-item --><\/p>\n<p><!-- wp:list-item --><\/p>\n<ol>\n<ol><\/ol>\n<\/ol>\n<p><!-- \/wp:list-item --><\/p>\n<p><!-- wp:list-item --><\/p>\n<ol>\n<ol><\/ol>\n<\/ol>\n<p><!-- \/wp:list-item --><\/p>\n<p><!-- \/wp:list --><\/p>\n<p><!-- wp:image {\"id\":2653,\"width\":823,\"height\":548,\"sizeSlug\":\"large\",\"linkDestination\":\"media\"} --><\/p>\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/i0.wp.com\/highupme.com\/wp-content\/uploads\/2023\/02\/Arbre-de-la-vie-small.png?ssl=1\" target=\"_blank\" rel=\"noreferrer noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/highupme.com\/wp-content\/uploads\/2023\/02\/Arbre-de-la-vie-small.png?resize=823%2C548&#038;ssl=1\" alt=\"\" class=\"wp-image-2653\" style=\"width: 823px; height: 548px;\" width=\"823\" height=\"548\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<figcaption class=\"wp-element-caption\">cliquez et enregistrez notre arbre de vie<\/figcaption>\n<\/figure>\n<p><!-- \/wp:image --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>PS: Il existe deux fa\u00e7ons de r\u00e9aliser votre arbre de vie. Il y a la m\u00e9thode cr\u00e9ative comme d\u00e9crite ci-dessus, je me sens l\u2019\u00e2me artistique et je dessine ou alors la fa\u00e7on j\u2019imprime et je m\u2019y mets.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Si vous optez pour la mani\u00e8re, je rempli les cases au gr\u00e9s de mes envies alors imprimez tout simplement notre\u00a0<strong>arbre de vie high up<\/strong>\u00a0<strong>me<\/strong>\u00a0que nous avons soigneusement r\u00e9alis\u00e9 pour vous. Vous le trouverez en cliquant le lien ci dessous.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:heading {\"level\":3} --><\/p>\n<h3 class=\"wp-block-heading\"><strong>Et pour conclure<\/strong><\/h3>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Soyez fiers de votre accomplissement! Vous avez laiss\u00e9 \u00e9merger votre cr\u00e9ativit\u00e9, vous avez suivi vos envies les plus folles et vous prenez finalement conscience de toutes vos belles qualit\u00e9s, n\u2019est-ce pas?<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:image {\"id\":1495,\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} --><\/p>\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"598\" src=\"https:\/\/i0.wp.com\/highupme.com\/wp-content\/uploads\/2022\/11\/happy.png?resize=800%2C598&#038;ssl=1\" alt=\"\" class=\"wp-image-1495\" srcset=\"https:\/\/highupme.com\/wp-content\/uploads\/2022\/11\/happy.png 800w, https:\/\/highupme.com\/wp-content\/uploads\/2022\/11\/happy-480x359.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><\/figure>\n<p><!-- \/wp:image --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Maintenant que votre arbre de vie a pris forme, il est temps de le mettre en valeur en l\u2019accrochant bien en \u00e9vidence de telle fa\u00e7on \u00e0 ce qu\u2019\u00e0 chaque fois que vous passez devant, il vous redonne ce bon coup de Boost de \u00ab\u00a0Confiance en soi\u00a0\u00bb<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>N\u2019h\u00e9sitez pas \u00e0 le modifier et \u00e0 la faire vivre au fil de vos nouvelles r\u00e9ussites et de vos nouveaux accomplissements. Une nouvelle qualit\u00e9 ou un nouvel objectif atteint et hop \u2026 Je le modifie!<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Nous esp\u00e9rons que cet exercice vous aura \u00e9t\u00e9 b\u00e9n\u00e9fique tout comme il l\u2019a \u00e9t\u00e9 pour nous!<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Et si vous souhaitez vous pencher un peu plus en profondeur sur vos d\u00e9sirs d\u2019accomplissements, vos changements, sur une am\u00e9lioration quelconque ou toute autre demande d\u2019ailleurs, alors sachez que nous sommes \u00e0 votre \u00e9coute.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-highupme wp-block-embed-highupme\">\n<div class=\"wp-block-embed__wrapper\"><\/div>\n<\/figure>\n<p><!-- \/wp:embed --><\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb custom_padding=\u00a0\u00bb||2px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbTitle\u00a0\u00bb _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbMontserrat||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#747d88&Prime; text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb1.9em\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bbMontserrat|700||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb42px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.3em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb max_width=\u00a0\u00bb700px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb4%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<h2>NOTRE PODCAST<\/h2>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<h3>Bienvenue dans La Capsule de Croissance \u00a9 !<\/h3>\n<p>Le podcast high up me \u00a9 qui explore le d\u00e9veloppement personnel\u2026 mais sans la langue de bois !<\/p>\n<p>Chaque premier lundi du mois, Laurent Biffi \u2013 Master Coach certifi\u00e9, praticien en PNL et membre de l&rsquo;ICF \u2013 vous embarque pour un voyage \u00e0 contre-courant du coaching traditionnel. Conversations profondes, critiques piquantes, histoires inspirantes et exercices concrets : ici, on parle croissance personnelle sans dogmes ni recettes miracles.<\/p>\n<p>Abonnez-vous d\u00e8s maintenant** et prenez votre dose mensuelle de r\u00e9flexion et d\u2019expansion. Pr\u00eat pour le d\u00e9collage ?<\/p>\n<p><strong>Inspirez, \u00c9coutez, Progressez.<\/strong><\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font=\u00a0\u00bbMontserrat|700||on|||||\u00a0\u00bb header_text_color=\u00a0\u00bb#f7f7f7&Prime; header_font_size=\u00a0\u00bb60px\u00a0\u00bb header_line_height=\u00a0\u00bb1.3em\u00a0\u00bb custom_margin=\u00a0\u00bb||40px|\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<h2 style=\"text-align: center;\"><strong><span style=\"color: #000000;\"><span style=\"color: #ffcc00;\">LA CAPSULE<\/span> <span style=\"color: #ffcc00;\">DE<\/span> CROISSANCE<\/span><\/strong><\/h2>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">Abonnez-vous pour ne rien manquer<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">Disponible sur toutes les plateformes\u00a0<\/span><\/p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/podcast.ausha.co\/la-capsule-de-croissance?s=1&Prime; button_text=\u00a0\u00bbS&rsquo;ABONNER\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_border_width=\u00a0\u00bb4px\u00a0\u00bb button_border_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb button_border_radius=\u00a0\u00bb100px\u00a0\u00bb button_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb button_font=\u00a0\u00bbMontserrat|on||on|\u00a0\u00bb button_icon=\u00a0\u00bb&#x45;||divi||400&Prime; button_icon_color=\u00a0\u00bb#747d88&Prime; animation_style=\u00a0\u00bbflip\u00a0\u00bb animation_direction=\u00a0\u00bbright\u00a0\u00bb animation_intensity_flip=\u00a0\u00bb20%\u00a0\u00bb button_text_color_hover=\u00a0\u00bb#747d88&Prime; button_border_color_hover=\u00a0\u00bb#747d88&Prime; button_letter_spacing_hover=\u00a0\u00bb2px\u00a0\u00bb button_bg_color_hover=\u00a0\u00bbrgba(0,0,0,0)\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bbon\u00a0\u00bb button_text_color__hover=\u00a0\u00bb#747d88&Prime; button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bbon\u00a0\u00bb button_border_color__hover=\u00a0\u00bb#747d88&Prime; button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bbon\u00a0\u00bb button_letter_spacing__hover=\u00a0\u00bb2px\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bbon\u00a0\u00bb button_bg_color__hover=\u00a0\u00bbrgba(0,0,0,0)\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/highupme.com\/wp-content\/uploads\/2023\/12\/IPHONE-1.png\u00a0\u00bb title_text=\u00a0\u00bbhigh up me podcast\u00a0\u00bb _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb18px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<iframe name=\"Ausha Podcast Player\" frameborder=\"0\" loading=\"lazy\" id=\"ausha-LyDm\" height=\"420\" style=\"border: none; width:100%; height:420px\" src=\"https:\/\/player.ausha.co\/?showId=YKVd5sgO2rMz&#038;color=%23e6b300&#038;display=horizontal&#038;multishow=true&#038;playlist=true&#038;v=3&#038;playerId=ausha-LyDm\"><\/iframe><script src=\"https:\/\/player.ausha.co\/ausha-player.js\"><\/script>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font=\u00a0\u00bbMontserrat|700||on|||||\u00a0\u00bb header_text_color=\u00a0\u00bb#f7f7f7&Prime; header_font_size=\u00a0\u00bb60px\u00a0\u00bb header_line_height=\u00a0\u00bb1.3em\u00a0\u00bb custom_margin=\u00a0\u00bb||40px|\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<h1 style=\"text-align: center;\"><span style=\"color: #ffcc00;\"><span style=\"caret-color: #ffcc00;\"><span style=\"color: #000000;\">Le 1er<\/span> lundi\u00a0<span style=\"color: #000000;\">du mois<\/span><\/span><\/span><\/h1>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_blurb url=\u00a0\u00bbhttps:\/\/smartlink.ausha.co\/la-capsule-de-croissance\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#xf144;||fa||900&Prime; icon_color=\u00a0\u00bb#fcd21d\u00a0\u00bb image_icon_width=\u00a0\u00bb60px\u00a0\u00bb _builder_version=\u00a0\u00bb4.22.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bbMontserrat|on|||\u00a0\u00bb header_text_color=\u00a0\u00bb#353740&Prime; header_font_size=\u00a0\u00bb22px\u00a0\u00bb header_line_height=\u00a0\u00bb1.4em\u00a0\u00bb body_font=\u00a0\u00bbMontserrat||||\u00a0\u00bb body_text_color=\u00a0\u00bb#747d88&Prime; body_font_size=\u00a0\u00bb16px\u00a0\u00bb body_line_height=\u00a0\u00bb1.8em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb custom_padding=\u00a0\u00bb30px|30px|30px|30px\u00a0\u00bb animation_style=\u00a0\u00bbzoom\u00a0\u00bb border_width_all=\u00a0\u00bb0px\u00a0\u00bb border_color_all=\u00a0\u00bb#dddddd\u00a0\u00bb border_style_all=\u00a0\u00bbsolid\u00a0\u00bb use_border_color=\u00a0\u00bbon\u00a0\u00bb border_color=\u00a0\u00bb#dddddd\u00a0\u00bb icon_font_size=\u00a0\u00bb60px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<h1><span lang=\"FR\">Disponible sur toutes les plateformes.<\/span><\/h1>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section]","protected":false},"excerpt":{"rendered":"<p>L\u2019arbre de vie est un outil que nous utilisons souvent avec nos clients. C\u2019est avant tout un excellent outil de partage bas\u00e9 sur les pratiques narratives et de soutien. Voyez les diff\u00e9rentes parties qui composent l\u2019arbre comme une m\u00e9taphore pour repr\u00e9senter les diff\u00e9rentes parties de votre vie.<\/p>","protected":false},"author":1,"featured_media":3023,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:paragraph -->\n<p><strong>L\u2019arbre de vie<\/strong>&nbsp;est un outil que nous utilisons souvent avec nos clients. C\u2019est avant tout un excellent outil de partage bas\u00e9 sur les pratiques narratives et de soutien. Voyez les diff\u00e9rentes parties qui composent l\u2019arbre comme une m\u00e9taphore pour repr\u00e9senter les diff\u00e9rentes parties de votre vie.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\"><strong>Explication<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Imaginez un arbre avec tout ce qui le compose et vous obtenez ceci:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><!-- wp:list-item -->\n<li><strong>Les racines<\/strong>&nbsp;repr\u00e9sentent vos&nbsp;origines, vos particularit\u00e9s, vos valeurs, vos passions et ce qui vous a fait grandir<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Le tronc<\/strong>&nbsp;repr\u00e9sente vos&nbsp;ressources, vos comp\u00e9tences, vos qualit\u00e9s, vos forces et ce que vous avez acquis<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Les grosses<\/strong>&nbsp;<strong>branches<\/strong>&nbsp;repr\u00e9sentent vos&nbsp;objectifs, vos projets \u00e0 long terme, vos espoirs et aspirations<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Les petites branches<\/strong>&nbsp;repr\u00e9sentent vos&nbsp;petits objectifs et d\u00e9fis du quotidien<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Les feuilles repr\u00e9sentent<\/strong>&nbsp;le personnes importantes de votre vie et les ressources autour de vous<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Les fruits et les fleurs<\/strong>&nbsp;repr\u00e9sentent vos r\u00e9sultats et les rencontres qui ont influenc\u00e9 votre vie de mani\u00e8re positive<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\"><strong>Pour qui et pourquoi ?<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Cet outil peut \u00eatre utilis\u00e9 \u00e0 tous les niveaux, qu\u2019ils soient d\u2019ordres personnels ou professionnels, en groupe ou en famille. Lors de notre s\u00e9ance de coaching&nbsp;<strong>high up me<\/strong>&nbsp;nous appliquons l\u2019art du questionnement justement et soigneusement formul\u00e9. De cette mani\u00e8re nous vous invitons \u00e0 faire un \u00e9tat des lieux de votre parcours avec un regard nouveau.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"id\":1488,\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} -->\n<figure class=\"wp-block-image size-full\"><img src=\"https:\/\/highupme.com\/wp-content\/uploads\/2022\/11\/questioning.png\" alt=\"\" class=\"wp-image-1488\"\/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>Vous pouvez utiliser de plusieurs fa\u00e7ons votre arbre de vie. Le domaines les plus courants sont:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><!-- wp:list-item -->\n<li>Booster et restaurer l\u2019estime de soi (<em>exemple mis en avant aujourd\u2019hui<\/em>).<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Se projeter dans l\u2019avenir.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Mieux se conna\u00eetre.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Mettre en place un projet.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Identifier les turbulences dans votre vie.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Op\u00e9rer une r\u00e9orientation professionnelle.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Changer de strat\u00e9gie.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Pr\u00e9venir, identifier et d\u00e9nouer des conflits.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>D\u00e9velopper la coh\u00e9sion d\u2019\u00e9quipes.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Construire ensemble une nouvelle fa\u00e7on de travailler.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Donner des feedbacks positifs et SMART.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>etc \u2026<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Comme vous l\u2019aurez tr\u00e8s certainement compris, l\u2019arbre de vie est un outil qui s\u2019adapte en fonction de votre demande et de vos attentes. En outre, vous n\u2019aurez pas besoin d\u2019une multitude de s\u00e9ances pour redonner du sens \u00e0 vos&nbsp;exp\u00e9riences pass\u00e9es&nbsp;de fa\u00e7on cr\u00e9ative et ludique, une seule suffira!<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Cet exercice est un excellent moyen de d\u00e9finir votre objectif global et ainsi de poser la trame de votre accompagnement avec nous pour vos futures s\u00e9ances&nbsp;<strong>high up me.<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\"><strong>Quels sont vos b\u00e9n\u00e9fices ?<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:list -->\n<ul><!-- wp:list-item -->\n<li>Augmenter votre estime de soi.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Mettre en avant vos valeurs.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Faire \u00e9merger vos ressources.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Avoir une vision plus claire, positive et plus objective de votre avenir.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Retrouvez&nbsp;l\u2019envie et le plaisir d\u2019agir et d\u2019avancer.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Transformer une exp\u00e9rience n\u00e9gative en un projet positif.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Booster votre confiance en vous.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Retrouver du sens.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Prendre conscience de vos comp\u00e9tences, vos talents et vos forces.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Trouver des pistes de r\u00e9orientation de mani\u00e8re plus cr\u00e9ative que le bilan de comp\u00e9tences habituel.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Rendre accessible vos projets et vos r\u00eaves.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Passer \u00e0 l\u2019action et devenir l\u2019acteur de votre vie.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Devenir la meilleure version de vous-m\u00eame.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Fixer vos limites.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Vous remettre en question.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>L\u2019arbre de vie est un super activateur d\u2019estime de soi et de confiance en soi&nbsp;! C\u2019est un bon coup de Boost dans la r\u00e9alisation de vos objectifs !<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\"><strong>Exercice \u00ab&nbsp;L\u2019arbre de l\u2019estime de soi&nbsp;\u00bb<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Je vous explique ci-dessous comment utiliser l\u2019arbre de vie afin de booster votre facteur estime de soi.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Ce mode d\u2019emploi est une des fa\u00e7ons d\u2019utiliser l\u2019arbre de vie. Il peut \u00eatre adapt\u00e9 et modifi\u00e9 en fonction de vos besoins. N\u2019h\u00e9sitez pas \u00e0 faire appel \u00e0 nous pour vos demandes de coaching et ensemble nous verrons ce qui vous convient le mieux en fonction de votre demande.<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Pour bien r\u00e9aliser votre arbre de l\u2019estime de soi vous aurez besoin de quelques outils essentiels.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ol><!-- wp:list-item -->\n<li>3 feuilles de papier.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>1 crayon gris et une gomme.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Des feutres ou des crayons de couleur.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Sur la premi\u00e8re feuille dressez une liste de vos qualit\u00e9s.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Sur la deuxi\u00e8me, faites une liste de vos r\u00e9ussites.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Sur la troisi\u00e8me, dessinez votre arbre.<!-- wp:list {\"ordered\":true} -->\n<ol><!-- wp:list-item -->\n<li>Tout d\u2019abord, dessinez le sol qui servira comme tout le monde le sait \u00e0 nourrir les racines de votre arbre et cr\u00e9er la s\u00e8ve.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Dessinez les racines de l\u2019arbre, bien \u00e9videment en dessous du sol nous sommes bien d\u2019accord. Elles lui permettront d\u2019assimiler les nutriments.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Ensuite vient le tronc. Il s\u2019\u00e9l\u00e8ve vers le ciel en devenant de plus en plus fort, ancr\u00e9 et plein de vie.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Maintenant viennent les branches qui s\u2019\u00e9tirent dans toutes les directions.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Les feuilles quant \u00e0 elles, sont l\u2019habit qui tient bon chaud si on part du principe que nous ne sommes ni en automne ni en hiver.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Et pour fini, cerise sur le Sundae, vous ajouterez les fleurs qui embelliront votre arbre et lui donneront les couleurs qui feront toute sa grandeur.<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list --><\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>A c\u00f4t\u00e9 de chaque fleur, inscrivez une r\u00e9ussite.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>A c\u00f4t\u00e9 de chaque racine, inscrivez une qualit\u00e9.<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:image {\"id\":2653,\"width\":823,\"height\":548,\"sizeSlug\":\"large\",\"linkDestination\":\"media\"} -->\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/highupme.com\/wp-content\/uploads\/2023\/02\/Arbre-de-la-vie-small.png\" target=\"_blank\" rel=\"noreferrer noopener\"><img src=\"https:\/\/highupme.com\/wp-content\/uploads\/2023\/02\/Arbre-de-la-vie-small-1024x683.png\" alt=\"\" class=\"wp-image-2653\" style=\"width:823px;height:548px\" width=\"823\" height=\"548\"\/><\/a><figcaption class=\"wp-element-caption\">cliquez et enregistrez notre arbre de vie<\/figcaption><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>PS: Il existe deux fa\u00e7ons de r\u00e9aliser votre arbre de vie. Il y a la m\u00e9thode cr\u00e9ative comme d\u00e9crite ci-dessus, je me sens l\u2019\u00e2me artistique et je dessine ou alors la fa\u00e7on j\u2019imprime et je m\u2019y mets.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Si vous optez pour la mani\u00e8re, je rempli les cases au gr\u00e9s de mes envies alors imprimez tout simplement notre&nbsp;<strong>arbre de vie high up<\/strong>&nbsp;<strong>me<\/strong>&nbsp;que nous avons soigneusement r\u00e9alis\u00e9 pour vous. Vous le trouverez en cliquant le lien ci dessous.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\"><strong>Et pour conclure<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Soyez fiers de votre accomplissement! Vous avez laiss\u00e9 \u00e9merger votre cr\u00e9ativit\u00e9, vous avez suivi vos envies les plus folles et vous prenez finalement conscience de toutes vos belles qualit\u00e9s, n\u2019est-ce pas?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"id\":1495,\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} -->\n<figure class=\"wp-block-image size-full\"><img src=\"https:\/\/highupme.com\/wp-content\/uploads\/2022\/11\/happy.png\" alt=\"\" class=\"wp-image-1495\"\/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>Maintenant que votre arbre de vie a pris forme, il est temps de le mettre en valeur en l\u2019accrochant bien en \u00e9vidence de telle fa\u00e7on \u00e0 ce qu\u2019\u00e0 chaque fois que vous passez devant, il vous redonne ce bon coup de Boost de \u00ab&nbsp;Confiance en soi&nbsp;\u00bb<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>N\u2019h\u00e9sitez pas \u00e0 le modifier et \u00e0 la faire vivre au fil de vos nouvelles r\u00e9ussites et de vos nouveaux accomplissements. Une nouvelle qualit\u00e9 ou un nouvel objectif atteint et hop \u2026 Je le modifie!<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Nous esp\u00e9rons que cet exercice vous aura \u00e9t\u00e9 b\u00e9n\u00e9fique tout comme il l\u2019a \u00e9t\u00e9 pour nous!<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Et si vous souhaitez vous pencher un peu plus en profondeur sur vos d\u00e9sirs d\u2019accomplissements, vos changements, sur une am\u00e9lioration quelconque ou toute autre demande d\u2019ailleurs, alors sachez que nous sommes \u00e0 votre \u00e9coute.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>A 2 c\u2019est toujours mieux !<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:embed {\"url\":\"https:\/\/highupme.com\/abonnez-vous\/\",\"type\":\"wp-embed\",\"providerNameSlug\":\"highupme\"} -->\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-highupme wp-block-embed-highupme\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/highupme.com\/abonnez-vous\/\n<\/div><\/figure>\n<!-- \/wp:embed -->","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[93,68],"tags":[71,70,72],"class_list":["post-2811","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coaching-dirigeants","category-coaching-de-vie","tag-confiance","tag-developpement-personnel","tag-estime-de-soi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L&#039;arbre de vie - Highupme<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/highupme.com\/en\/arbre-de-vie\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;arbre de vie - Highupme\" \/>\n<meta property=\"og:description\" content=\"L\u2019arbre de vie est un outil que nous utilisons souvent avec nos clients. C\u2019est avant tout un excellent outil de partage bas\u00e9 sur les pratiques narratives et de soutien. Voyez les diff\u00e9rentes parties qui composent l\u2019arbre comme une m\u00e9taphore pour repr\u00e9senter les diff\u00e9rentes parties de votre vie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/highupme.com\/en\/arbre-de-vie\/\" \/>\n<meta property=\"og:site_name\" content=\"Highupme\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-14T17:52:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-09T12:02:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/highupme.com\/wp-content\/uploads\/2023\/03\/larbre-de-vie.png?fit=800%2C500&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Laurent Biffi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laurent Biffi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/highupme.com\/arbre-de-vie\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/highupme.com\/arbre-de-vie\/\"},\"author\":{\"name\":\"Laurent Biffi\",\"@id\":\"https:\/\/highupme.com\/en\/#\/schema\/person\/0b93169013cd562c91cbbc0cfe22185e\"},\"headline\":\"L&rsquo;arbre de vie\",\"datePublished\":\"2023-03-14T17:52:27+00:00\",\"dateModified\":\"2025-02-09T12:02:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/highupme.com\/arbre-de-vie\/\"},\"wordCount\":2247,\"publisher\":{\"@id\":\"https:\/\/highupme.com\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/highupme.com\/arbre-de-vie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/highupme.com\/wp-content\/uploads\/2023\/03\/larbre-de-vie.png?fit=800%2C500&ssl=1\",\"keywords\":[\"confiance\",\"d\u00e9veloppement personnel\",\"estime de soi\"],\"articleSection\":[\"Coaching de dirigeants\",\"Coaching de vie\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/highupme.com\/arbre-de-vie\/\",\"url\":\"https:\/\/highupme.com\/arbre-de-vie\/\",\"name\":\"L'arbre de vie - Highupme\",\"isPartOf\":{\"@id\":\"https:\/\/highupme.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/highupme.com\/arbre-de-vie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/highupme.com\/arbre-de-vie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/highupme.com\/wp-content\/uploads\/2023\/03\/larbre-de-vie.png?fit=800%2C500&ssl=1\",\"datePublished\":\"2023-03-14T17:52:27+00:00\",\"dateModified\":\"2025-02-09T12:02:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/highupme.com\/arbre-de-vie\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/highupme.com\/arbre-de-vie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/highupme.com\/arbre-de-vie\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/highupme.com\/wp-content\/uploads\/2023\/03\/larbre-de-vie.png?fit=800%2C500&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/highupme.com\/wp-content\/uploads\/2023\/03\/larbre-de-vie.png?fit=800%2C500&ssl=1\",\"width\":800,\"height\":500,\"caption\":\"L\u2019arbre de vie est un outil que nous utilisons souvent avec nos clients. C\u2019est avant tout un excellent outil de partage bas\u00e9 sur les pratiques narratives et de soutien.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/highupme.com\/arbre-de-vie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/highupme.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;arbre de vie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/highupme.com\/en\/#website\",\"url\":\"https:\/\/highupme.com\/en\/\",\"name\":\"Highupme\",\"description\":\"The Coaching Company\",\"publisher\":{\"@id\":\"https:\/\/highupme.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/highupme.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/highupme.com\/en\/#organization\",\"name\":\"Highupme\",\"url\":\"https:\/\/highupme.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/highupme.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i0.wp.com\/highupme.com\/wp-content\/uploads\/2022\/12\/highupme-logo-PNG.png?fit=500%2C311&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/highupme.com\/wp-content\/uploads\/2022\/12\/highupme-logo-PNG.png?fit=500%2C311&ssl=1\",\"width\":500,\"height\":311,\"caption\":\"Highupme\"},\"image\":{\"@id\":\"https:\/\/highupme.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/high_up_me\/\",\"https:\/\/www.linkedin.com\/company\/high-up-me\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/highupme.com\/en\/#\/schema\/person\/0b93169013cd562c91cbbc0cfe22185e\",\"name\":\"Laurent Biffi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/highupme.com\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/highupme.com\/wp-content\/uploads\/2022\/11\/54430D0B-0CF4-420D-A2C3-9DF57CA263F3.jpeg\",\"contentUrl\":\"https:\/\/highupme.com\/wp-content\/uploads\/2022\/11\/54430D0B-0CF4-420D-A2C3-9DF57CA263F3.jpeg\",\"caption\":\"Laurent Biffi\"},\"sameAs\":[\"https:\/\/highupme.com\"],\"url\":\"https:\/\/highupme.com\/en\/author\/lbihighupme\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'arbre de vie - Highupme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/highupme.com\/en\/arbre-de-vie\/","og_locale":"en_GB","og_type":"article","og_title":"L'arbre de vie - Highupme","og_description":"L\u2019arbre de vie est un outil que nous utilisons souvent avec nos clients. C\u2019est avant tout un excellent outil de partage bas\u00e9 sur les pratiques narratives et de soutien. Voyez les diff\u00e9rentes parties qui composent l\u2019arbre comme une m\u00e9taphore pour repr\u00e9senter les diff\u00e9rentes parties de votre vie.","og_url":"https:\/\/highupme.com\/en\/arbre-de-vie\/","og_site_name":"Highupme","article_published_time":"2023-03-14T17:52:27+00:00","article_modified_time":"2025-02-09T12:02:25+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/i0.wp.com\/highupme.com\/wp-content\/uploads\/2023\/03\/larbre-de-vie.png?fit=800%2C500&ssl=1","type":"image\/png"}],"author":"Laurent Biffi","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Laurent Biffi","Estimated reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/highupme.com\/arbre-de-vie\/#article","isPartOf":{"@id":"https:\/\/highupme.com\/arbre-de-vie\/"},"author":{"name":"Laurent Biffi","@id":"https:\/\/highupme.com\/en\/#\/schema\/person\/0b93169013cd562c91cbbc0cfe22185e"},"headline":"L&rsquo;arbre de vie","datePublished":"2023-03-14T17:52:27+00:00","dateModified":"2025-02-09T12:02:25+00:00","mainEntityOfPage":{"@id":"https:\/\/highupme.com\/arbre-de-vie\/"},"wordCount":2247,"publisher":{"@id":"https:\/\/highupme.com\/en\/#organization"},"image":{"@id":"https:\/\/highupme.com\/arbre-de-vie\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/highupme.com\/wp-content\/uploads\/2023\/03\/larbre-de-vie.png?fit=800%2C500&ssl=1","keywords":["confiance","d\u00e9veloppement personnel","estime de soi"],"articleSection":["Coaching de dirigeants","Coaching de vie"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/highupme.com\/arbre-de-vie\/","url":"https:\/\/highupme.com\/arbre-de-vie\/","name":"L'arbre de vie - Highupme","isPartOf":{"@id":"https:\/\/highupme.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/highupme.com\/arbre-de-vie\/#primaryimage"},"image":{"@id":"https:\/\/highupme.com\/arbre-de-vie\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/highupme.com\/wp-content\/uploads\/2023\/03\/larbre-de-vie.png?fit=800%2C500&ssl=1","datePublished":"2023-03-14T17:52:27+00:00","dateModified":"2025-02-09T12:02:25+00:00","breadcrumb":{"@id":"https:\/\/highupme.com\/arbre-de-vie\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/highupme.com\/arbre-de-vie\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/highupme.com\/arbre-de-vie\/#primaryimage","url":"https:\/\/i0.wp.com\/highupme.com\/wp-content\/uploads\/2023\/03\/larbre-de-vie.png?fit=800%2C500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/highupme.com\/wp-content\/uploads\/2023\/03\/larbre-de-vie.png?fit=800%2C500&ssl=1","width":800,"height":500,"caption":"L\u2019arbre de vie est un outil que nous utilisons souvent avec nos clients. C\u2019est avant tout un excellent outil de partage bas\u00e9 sur les pratiques narratives et de soutien."},{"@type":"BreadcrumbList","@id":"https:\/\/highupme.com\/arbre-de-vie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/highupme.com\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;arbre de vie"}]},{"@type":"WebSite","@id":"https:\/\/highupme.com\/en\/#website","url":"https:\/\/highupme.com\/en\/","name":"Highupme","description":"The Coaching Company","publisher":{"@id":"https:\/\/highupme.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/highupme.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/highupme.com\/en\/#organization","name":"Highupme","url":"https:\/\/highupme.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/highupme.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/highupme.com\/wp-content\/uploads\/2022\/12\/highupme-logo-PNG.png?fit=500%2C311&ssl=1","contentUrl":"https:\/\/i0.wp.com\/highupme.com\/wp-content\/uploads\/2022\/12\/highupme-logo-PNG.png?fit=500%2C311&ssl=1","width":500,"height":311,"caption":"Highupme"},"image":{"@id":"https:\/\/highupme.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/high_up_me\/","https:\/\/www.linkedin.com\/company\/high-up-me"]},{"@type":"Person","@id":"https:\/\/highupme.com\/en\/#\/schema\/person\/0b93169013cd562c91cbbc0cfe22185e","name":"Laurent Biffi","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/highupme.com\/en\/#\/schema\/person\/image\/","url":"https:\/\/highupme.com\/wp-content\/uploads\/2022\/11\/54430D0B-0CF4-420D-A2C3-9DF57CA263F3.jpeg","contentUrl":"https:\/\/highupme.com\/wp-content\/uploads\/2022\/11\/54430D0B-0CF4-420D-A2C3-9DF57CA263F3.jpeg","caption":"Laurent Biffi"},"sameAs":["https:\/\/highupme.com"],"url":"https:\/\/highupme.com\/en\/author\/lbihighupme\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/highupme.com\/wp-content\/uploads\/2023\/03\/larbre-de-vie.png?fit=800%2C500&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/highupme.com\/en\/wp-json\/wp\/v2\/posts\/2811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/highupme.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/highupme.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/highupme.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/highupme.com\/en\/wp-json\/wp\/v2\/comments?post=2811"}],"version-history":[{"count":0,"href":"https:\/\/highupme.com\/en\/wp-json\/wp\/v2\/posts\/2811\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/highupme.com\/en\/wp-json\/wp\/v2\/media\/3023"}],"wp:attachment":[{"href":"https:\/\/highupme.com\/en\/wp-json\/wp\/v2\/media?parent=2811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/highupme.com\/en\/wp-json\/wp\/v2\/categories?post=2811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/highupme.com\/en\/wp-json\/wp\/v2\/tags?post=2811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}